{"id":13045,"date":"2024-03-10T18:34:26","date_gmt":"2024-03-10T17:34:26","guid":{"rendered":"https:\/\/www.hotelaigle.it\/?page_id=13045"},"modified":"2024-03-10T18:37:11","modified_gmt":"2024-03-10T17:37:11","slug":"livre-dor","status":"publish","type":"page","link":"https:\/\/www.hotelaigle.it\/fr\/prestations-de-service\/livre-dor\/","title":{"rendered":"Livre d&rsquo;Or"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13045\" class=\"elementor elementor-13045 elementor-12998\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db55fa5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db55fa5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7043a98\" data-id=\"7043a98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3bf31e elementor-widget elementor-widget-text-editor\" data-id=\"f3bf31e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<figure id=\"attachment_13019\" aria-describedby=\"caption-attachment-13019\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-13019 size-medium\" src=\"https:\/\/www.hotelaigle.it\/wp-content\/uploads\/2024\/03\/istockphoto-1143254038-612x612-1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.hotelaigle.it\/wp-content\/uploads\/2024\/03\/istockphoto-1143254038-612x612-1-300x300.jpg 300w, https:\/\/www.hotelaigle.it\/wp-content\/uploads\/2024\/03\/istockphoto-1143254038-612x612-1-150x150.jpg 150w, https:\/\/www.hotelaigle.it\/wp-content\/uploads\/2024\/03\/istockphoto-1143254038-612x612-1-250x250.jpg 250w, https:\/\/www.hotelaigle.it\/wp-content\/uploads\/2024\/03\/istockphoto-1143254038-612x612-1-512x512.jpg 512w, https:\/\/www.hotelaigle.it\/wp-content\/uploads\/2024\/03\/istockphoto-1143254038-612x612-1.jpg 612w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-13019\" class=\"wp-caption-text\">Livre d&rsquo;or de l&rsquo;Hotel Aigle<\/figcaption><\/figure><p>Ceci est notre <strong>livre d&rsquo;or<\/strong>. Laissez votre commentaire, un message d&rsquo;accueil, vos impressions, partagez une photo de votre s\u00e9jour, ajoutez une l\u00e9gende. Malheureusement, avec l&rsquo;\u00e9volution des temps et de la technologie, les cartes postales tant appr\u00e9ci\u00e9es n&rsquo;arrivent plus, ni les lettres avec un Polaroid \u00e0 l&rsquo;int\u00e9rieur qui avaient captur\u00e9 un moment sp\u00e9cial avec ces couleurs particuli\u00e8res et cette saveur que seules les photos du pass\u00e9 pouvaient transmettre. Mais aujourd&rsquo;hui, gr\u00e2ce \u00e0 ce \u00ab\u00a0<strong>babillard virtuel<\/strong>\u00ab\u00a0, nous pouvons nous rapprocher de ces \u00e9motions, en partageant ici des \u00e9motions, des souvenirs, des sensations et un salut qui est toujours, du moins dans l&rsquo;intention, un <strong>AUREVOIR<\/strong>.<br \/>Merci pour vos commentaires, sur ce babillard o\u00f9 nous lirons et relirons chacun de vos messages, qui nous rappelleront votre visite, et aussi la raison pour laquelle nous sommes l\u00e0 pour vous depuis plus de vingt ans.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5355959 elementor-widget elementor-widget-text-editor\" data-id=\"5355959\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"text-indent: 0em; text-align: inherit;\"><strong>VOIR LE<\/strong>\u00a0: <a href=\"https:\/\/padlet.com\/hotelaiglecourmayeur\/guestbook\" target=\"_blank\" rel=\"noopener\">Livre d&rsquo;Or<\/a><\/span><span style=\"text-indent: 0em; text-align: inherit;\">\u00a0<\/span><\/p><p><strong><a href=\"https:\/\/padlet.com\/hotelaiglecourmayeur\/submission-request\/Y8RAzJL1qn5KvxV9\" target=\"_blank\" rel=\"noopener\">LAISSER UN MESSAGE DANS LE LIVRE D\u2019OR<\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ceci est notre livre d&rsquo;or. Laissez votre commentaire, un message d&rsquo;accueil, vos impressions, partagez une photo de votre s\u00e9jour, ajoutez une l\u00e9gende. Malheureusement, avec l&rsquo;\u00e9volution des temps et de la technologie, les cartes postales tant appr\u00e9ci\u00e9es n&rsquo;arrivent plus, ni les lettres avec un Polaroid \u00e0 l&rsquo;int\u00e9rieur qui avaient captur\u00e9 un &hellip;<\/p>\n","protected":false},"author":2,"featured_media":12541,"parent":12585,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13045","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.hotelaigle.it\/fr\/wp-json\/wp\/v2\/pages\/13045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelaigle.it\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelaigle.it\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelaigle.it\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelaigle.it\/fr\/wp-json\/wp\/v2\/comments?post=13045"}],"version-history":[{"count":4,"href":"https:\/\/www.hotelaigle.it\/fr\/wp-json\/wp\/v2\/pages\/13045\/revisions"}],"predecessor-version":[{"id":13049,"href":"https:\/\/www.hotelaigle.it\/fr\/wp-json\/wp\/v2\/pages\/13045\/revisions\/13049"}],"up":[{"embeddable":true,"href":"https:\/\/www.hotelaigle.it\/fr\/wp-json\/wp\/v2\/pages\/12585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hotelaigle.it\/fr\/wp-json\/wp\/v2\/media\/12541"}],"wp:attachment":[{"href":"https:\/\/www.hotelaigle.it\/fr\/wp-json\/wp\/v2\/media?parent=13045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}